{"id":4126,"date":"2013-07-03T09:16:19","date_gmt":"2013-07-03T07:16:19","guid":{"rendered":"https:\/\/blog.truckscout24.com\/de\/?p=1112"},"modified":"2014-04-15T17:14:14","modified_gmt":"2014-04-15T15:14:14","slug":"funzionamento-anomalo-per-il-sistema-elettronico-di-pedaggio","status":"publish","type":"post","link":"https:\/\/blog.truckscout24.com\/it\/leggi-normative\/funzionamento-anomalo-per-il-sistema-elettronico-di-pedaggio\/","title":{"rendered":"Funzionamento anomalo per il sistema elettronico di pedaggio"},"content":{"rendered":"<figure id=\"attachment_1117\" aria-describedby=\"caption-attachment-1117\" style=\"width: 898px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/blog.truckscout24.com\/de\/wp-content\/uploads\/2013\/07\/Autobahn-Ungarn-19-fotoshowImageNew-4f27c456-49020.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1117\" alt=\"Funzionamento anomalo per il sistema elettronico di pedaggio\" src=\"https:\/\/blog.truckscout24.com\/de\/wp-content\/uploads\/2013\/07\/Autobahn-Ungarn-19-fotoshowImageNew-4f27c456-49020.jpg\" width=\"898\" height=\"599\" \/><\/a><figcaption id=\"caption-attachment-1117\" class=\"wp-caption-text\">Euro Transport Media<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Dal 1\u00b0 luglio in Ungheria \u00e8 stato introdotto il sistema elettronico di pedaggio autostradale per camion HU-GO: gi\u00e0 dopo poche ore i pareri erano discordanti.<\/p>\n<p>Secondo quanto riportato nella pagina Web della rivista specializzata austriaca &#8220;Industriemagazin&#8221;, fra le ore 1.00 &#8211; 3.00 e le\u00a0 ore 7.30 &#8211; 10.00 si sarebbero verificate interruzioni del sistema. La societ\u00e0 autostradale ungherese AAK, che ha adottato il sistema HU-GO, si \u00e8 espressa in modo approssimativo parlando di &#8220;attacchi al sistema&#8221; che avrebbero causato un sovraccarico.<\/p>\n<h2>Il sistema\u00a0 di pedaggio autostradale per camion non \u00e8 stato testato<\/h2>\n<p>L&#8217;associazione degli automobilisti ungheresi ha approfittato del disservizio per criticare l&#8217;adozione del sistema HU-GO, definendola &#8220;prematura&#8221;. Gabor Karmos, segretario generale dell&#8217;associazione, ha fatto presente che prima della messa in funzione del sistema gli esperti avevano messo in guardia sull&#8217;eventualit\u00e0 di possibili disagi causati dalla mancanza di una fase di test. In Germania il periodo di prova sarebbe durato un anno e in Slovacchia nove mesi.<\/p>\n<p>Dai dati forniti dal governo ungherese, finora 60.000 veicoli ungheresi risultano registrati al sistema di pedaggio autostradale elettronico per camion. Il sistema \u00e8 stato impiegato su una rete stradale di 6.318 chilometri: lo stato ungherese prevede un incasso annuo di circa 250 milioni di euro.<\/p>\n<p>Secondo le indicazioni fornite dall&#8217;AIS\u00d6, l&#8217;associazione nazionale austriaca degli autotrasportatori, le tariffe per il pedaggio dipendono dalla categoria di veicolo e dalla classe di emissioni nonch\u00e9 dalla distanza percorsa. Le fasce di prezzo sono le seguenti: da 39,29 HUF\/km a 85,34 HUF\/km su autostrade e strade con diritto di precedenza e da 16,72 HUF\/km a 53,23 HUF\/km su sulle strade principali (10,- HUF = 0,035 EUR).<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Dal 1\u00b0 luglio in Ungheria \u00e8 stato introdotto il sistema elettronico di pedaggio autostradale per camion HU-GO: gi\u00e0 dopo poche ore i pareri erano discordanti. Secondo quanto riportato nella pagina Web della rivista specializzata austriaca &#8220;Industriemagazin&#8221;, fra le ore 1.00 &#8211; 3.00 e le\u00a0 ore 7.30 &#8211; 10.00 si sarebbero verificate interruzioni del sistema. &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blog.truckscout24.com\/it\/leggi-normative\/funzionamento-anomalo-per-il-sistema-elettronico-di-pedaggio\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Funzionamento anomalo per il sistema elettronico di pedaggio&#8221;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":4656,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[4],"tags":[323,132,159],"class_list":["post-4126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-leggi-normative","tag-autocarri","tag-sistema-pedaggio","tag-ungheria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Funzionamento anomalo per il sistema elettronico di pedaggio - TruckScout24 Blog<\/title>\n<meta name=\"description\" content=\"Dal 1\u00b0 luglio in Ungheria \u00e8 stato introdotto il sistema elettronico di pedaggio autostradale per camion HU-GO: gi\u00e0 dopo poche ore i pareri erano discordanti.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.truckscout24.com\/it\/leggi-normative\/funzionamento-anomalo-per-il-sistema-elettronico-di-pedaggio\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Funzionamento anomalo per il sistema elettronico di pedaggio - TruckScout24 Blog\" \/>\n<meta property=\"og:description\" content=\"Dal 1\u00b0 luglio in Ungheria \u00e8 stato introdotto il sistema elettronico di pedaggio autostradale per camion HU-GO: gi\u00e0 dopo poche ore i pareri erano discordanti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.truckscout24.com\/it\/leggi-normative\/funzionamento-anomalo-per-il-sistema-elettronico-di-pedaggio\/\" \/>\n<meta property=\"og:site_name\" content=\"TruckScout24 Blog\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-03T07:16:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-04-15T15:14:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.truckscout24.com\/it\/wp-content\/uploads\/sites\/5\/2014\/03\/Autobahn-Ungarn-19-fotoshowImageNew-4f27c456-490201.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.truckscout24.com\/it\/#website\",\"url\":\"https:\/\/blog.truckscout24.com\/it\/\",\"name\":\"TruckScout24 Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.truckscout24.com\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/blog.truckscout24.com\/it\/leggi-normative\/funzionamento-anomalo-per-il-sistema-elettronico-di-pedaggio\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/blog.truckscout24.com\/it\/wp-content\/uploads\/sites\/5\/2014\/03\/Autobahn-Ungarn-19-fotoshowImageNew-4f27c456-490201.jpg\",\"contentUrl\":\"https:\/\/blog.truckscout24.com\/it\/wp-content\/uploads\/sites\/5\/2014\/03\/Autobahn-Ungarn-19-fotoshowImageNew-4f27c456-490201.jpg\",\"width\":300,\"height\":200},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.truckscout24.com\/it\/leggi-normative\/funzionamento-anomalo-per-il-sistema-elettronico-di-pedaggio\/#webpage\",\"url\":\"https:\/\/blog.truckscout24.com\/it\/leggi-normative\/funzionamento-anomalo-per-il-sistema-elettronico-di-pedaggio\/\",\"name\":\"Funzionamento anomalo per il sistema elettronico di pedaggio - TruckScout24 Blog\",\"isPartOf\":{\"@id\":\"https:\/\/blog.truckscout24.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.truckscout24.com\/it\/leggi-normative\/funzionamento-anomalo-per-il-sistema-elettronico-di-pedaggio\/#primaryimage\"},\"datePublished\":\"2013-07-03T07:16:19+00:00\",\"dateModified\":\"2014-04-15T15:14:14+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Dal 1\u00b0 luglio in Ungheria \u00e8 stato introdotto il sistema elettronico di pedaggio autostradale per camion HU-GO: gi\u00e0 dopo poche ore i pareri erano discordanti.\",\"breadcrumb\":{\"@id\":\"https:\/\/blog.truckscout24.com\/it\/leggi-normative\/funzionamento-anomalo-per-il-sistema-elettronico-di-pedaggio\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.truckscout24.com\/it\/leggi-normative\/funzionamento-anomalo-per-il-sistema-elettronico-di-pedaggio\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.truckscout24.com\/it\/leggi-normative\/funzionamento-anomalo-per-il-sistema-elettronico-di-pedaggio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.truckscout24.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Funzionamento anomalo per il sistema elettronico di pedaggio\"}]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/blog.truckscout24.com\/it\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Funzionamento anomalo per il sistema elettronico di pedaggio - TruckScout24 Blog","description":"Dal 1\u00b0 luglio in Ungheria \u00e8 stato introdotto il sistema elettronico di pedaggio autostradale per camion HU-GO: gi\u00e0 dopo poche ore i pareri erano discordanti.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.truckscout24.com\/it\/leggi-normative\/funzionamento-anomalo-per-il-sistema-elettronico-di-pedaggio\/","og_locale":"en_US","og_type":"article","og_title":"Funzionamento anomalo per il sistema elettronico di pedaggio - TruckScout24 Blog","og_description":"Dal 1\u00b0 luglio in Ungheria \u00e8 stato introdotto il sistema elettronico di pedaggio autostradale per camion HU-GO: gi\u00e0 dopo poche ore i pareri erano discordanti.","og_url":"https:\/\/blog.truckscout24.com\/it\/leggi-normative\/funzionamento-anomalo-per-il-sistema-elettronico-di-pedaggio\/","og_site_name":"TruckScout24 Blog","article_published_time":"2013-07-03T07:16:19+00:00","article_modified_time":"2014-04-15T15:14:14+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/blog.truckscout24.com\/it\/wp-content\/uploads\/sites\/5\/2014\/03\/Autobahn-Ungarn-19-fotoshowImageNew-4f27c456-490201.jpg","type":"image\/jpeg"}],"twitter_misc":{"Written by":"","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/blog.truckscout24.com\/it\/#website","url":"https:\/\/blog.truckscout24.com\/it\/","name":"TruckScout24 Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.truckscout24.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/blog.truckscout24.com\/it\/leggi-normative\/funzionamento-anomalo-per-il-sistema-elettronico-di-pedaggio\/#primaryimage","inLanguage":"en-US","url":"https:\/\/blog.truckscout24.com\/it\/wp-content\/uploads\/sites\/5\/2014\/03\/Autobahn-Ungarn-19-fotoshowImageNew-4f27c456-490201.jpg","contentUrl":"https:\/\/blog.truckscout24.com\/it\/wp-content\/uploads\/sites\/5\/2014\/03\/Autobahn-Ungarn-19-fotoshowImageNew-4f27c456-490201.jpg","width":300,"height":200},{"@type":"WebPage","@id":"https:\/\/blog.truckscout24.com\/it\/leggi-normative\/funzionamento-anomalo-per-il-sistema-elettronico-di-pedaggio\/#webpage","url":"https:\/\/blog.truckscout24.com\/it\/leggi-normative\/funzionamento-anomalo-per-il-sistema-elettronico-di-pedaggio\/","name":"Funzionamento anomalo per il sistema elettronico di pedaggio - TruckScout24 Blog","isPartOf":{"@id":"https:\/\/blog.truckscout24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.truckscout24.com\/it\/leggi-normative\/funzionamento-anomalo-per-il-sistema-elettronico-di-pedaggio\/#primaryimage"},"datePublished":"2013-07-03T07:16:19+00:00","dateModified":"2014-04-15T15:14:14+00:00","author":{"@id":""},"description":"Dal 1\u00b0 luglio in Ungheria \u00e8 stato introdotto il sistema elettronico di pedaggio autostradale per camion HU-GO: gi\u00e0 dopo poche ore i pareri erano discordanti.","breadcrumb":{"@id":"https:\/\/blog.truckscout24.com\/it\/leggi-normative\/funzionamento-anomalo-per-il-sistema-elettronico-di-pedaggio\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.truckscout24.com\/it\/leggi-normative\/funzionamento-anomalo-per-il-sistema-elettronico-di-pedaggio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.truckscout24.com\/it\/leggi-normative\/funzionamento-anomalo-per-il-sistema-elettronico-di-pedaggio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.truckscout24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Funzionamento anomalo per il sistema elettronico di pedaggio"}]},{"@type":"Person","@id":"","url":"https:\/\/blog.truckscout24.com\/it\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.truckscout24.com\/it\/wp-json\/wp\/v2\/posts\/4126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.truckscout24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.truckscout24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.truckscout24.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.truckscout24.com\/it\/wp-json\/wp\/v2\/comments?post=4126"}],"version-history":[{"count":1,"href":"https:\/\/blog.truckscout24.com\/it\/wp-json\/wp\/v2\/posts\/4126\/revisions"}],"predecessor-version":[{"id":4657,"href":"https:\/\/blog.truckscout24.com\/it\/wp-json\/wp\/v2\/posts\/4126\/revisions\/4657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.truckscout24.com\/it\/wp-json\/wp\/v2\/media\/4656"}],"wp:attachment":[{"href":"https:\/\/blog.truckscout24.com\/it\/wp-json\/wp\/v2\/media?parent=4126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.truckscout24.com\/it\/wp-json\/wp\/v2\/categories?post=4126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.truckscout24.com\/it\/wp-json\/wp\/v2\/tags?post=4126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}